{"id":238,"date":"2021-11-25T14:38:20","date_gmt":"2021-11-25T14:38:20","guid":{"rendered":"https:\/\/moisesetlaurence.com\/home\/"},"modified":"2025-04-03T15:17:58","modified_gmt":"2025-04-03T15:17:58","slug":"accueil","status":"publish","type":"page","link":"https:\/\/moisesetlaurence.com\/fr\/","title":{"rendered":"Accueil"},"content":{"rendered":"<div id='av_section_1'  class='avia-section av-2x6nx-251c3ff094bfbbad48f04eb38a407ddf main_color avia-section-large avia-no-border-styling  avia-builder-el-0  el_before_av_layout_row  avia-builder-el-first  avia-bg-style-scroll  container_wrap fullsize'  ><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-238'><div class='entry-content-wrapper clearfix'>\n<div class='flex_column_table av-1v7ud-06e234ef0918ece6a1e5bf873fb1a2c4 sc-av_one_half av-equal-height-column-flextable'><div class='flex_column av-1v7ud-06e234ef0918ece6a1e5bf873fb1a2c4 av_one_half  avia-builder-el-1  el_before_av_one_half  avia-builder-el-first  first flex_column_table_cell av-equal-height-column av-align-middle '   ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kwksia08-ac589fcd231b66703e6d73d1cc4b348e\">\n.avia-image-container.av-kwksia08-ac589fcd231b66703e6d73d1cc4b348e .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-kwksia08-ac589fcd231b66703e6d73d1cc4b348e av-styling-no-styling avia-align-center  avia-builder-el-2  avia-builder-el-no-sibling  '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" class='wp-image-191 avia-img-lazy-loading-not-191 avia_image' src=\"https:\/\/moisesetlaurence.com\/wp-content\/uploads\/2025\/03\/photo1_ML.jpg\" alt='' title='photo1_ML'  height=\"1099\" width=\"825\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/moisesetlaurence.com\/wp-content\/uploads\/2025\/03\/photo1_ML.jpg 825w, https:\/\/moisesetlaurence.com\/wp-content\/uploads\/2025\/03\/photo1_ML-225x300.jpg 225w, https:\/\/moisesetlaurence.com\/wp-content\/uploads\/2025\/03\/photo1_ML-773x1030.jpg 773w, https:\/\/moisesetlaurence.com\/wp-content\/uploads\/2025\/03\/photo1_ML-768x1023.jpg 768w, https:\/\/moisesetlaurence.com\/wp-content\/uploads\/2025\/03\/photo1_ML-529x705.jpg 529w\" sizes=\"(max-width: 825px) 100vw, 825px\" \/><\/div><\/div><\/div><\/div><div class='av-flex-placeholder'><\/div><div class='flex_column av-1y0uh-9c686413e878ce95d4eee6f67e6e20bb av_one_half  avia-builder-el-3  el_after_av_one_half  avia-builder-el-last  flex_column_table_cell av-equal-height-column av-align-middle '   ><section  class='av_textblock_section av-m7tbnksu-775285c8bbb811d71d7e7066736cf199 '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p style=\"text-align: center;\"><span style=\"font-size: 130%; letter-spacing: 0.30em;\">MOISES<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 130%; letter-spacing: 0.30em;\">&amp;<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 130%; letter-spacing: 0.30em;\">LAURENCE<\/span><\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-14amp-8dffcd7c05ea75b597dcfce786207787\">\n#top .hr.hr-invisible.av-14amp-8dffcd7c05ea75b597dcfce786207787{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-14amp-8dffcd7c05ea75b597dcfce786207787 hr-invisible  avia-builder-el-5  el_after_av_textblock  el_before_av_textblock  '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-w6i1-d0e575e8e26252a2e13fc93bea897687 '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-139 aligncenter\" role=\"img\" src=\"https:\/\/moisesetlaurence.com\/wp-content\/uploads\/2025\/03\/save-the-date.svg\" alt=\"\" width=\"300\" height=\"75\" \/><\/p>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-99mql-eb6e64eb828f7ce483b42ca789025fc1 '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p style=\"text-align: center;\"><span style=\"font-size: 100%;\">Treize septembre deux mille vingt-cinq<\/span><\/p>\n<\/div><\/section><br \/>\n<div  class='av-countdown-timer av-m7tglx7c-b39f8f0e3cd0005265ad13c3bbe39505 av-align-center av-default-style  avia-builder-el-8  el_after_av_textblock  avia-builder-el-last  '  data-year=' 2025' data-month='8' data-day=' 13 ' data-hour='15' data-minute='0' data-timezone='0' data-interval='1000' data-maximum='5' ><span class='av-countdown-timer-inner'><span class='av-countdown-cell av-countdown-weeks'><span class='av-countdown-cell-inner'><span class='av-countdown-time ' data-upate-width='weeks'>0<\/span><span class='av-countdown-time-label ' data-label='Semaine' data-label-multi='Semaines'>Semaines<\/span><\/span><\/span><span class='av-countdown-cell av-countdown-days'><span class='av-countdown-cell-inner'><span class='av-countdown-time ' data-upate-width='days'>0<\/span><span class='av-countdown-time-label ' data-label='Jour' data-label-multi='Jours'>Jours<\/span><\/span><\/span><span class='av-countdown-cell av-countdown-hours'><span class='av-countdown-cell-inner'><span class='av-countdown-time ' data-upate-width='hours'>0<\/span><span class='av-countdown-time-label ' data-label='Heure' data-label-multi='Heures'>Heures<\/span><\/span><\/span><span class='av-countdown-cell av-countdown-minutes'><span class='av-countdown-cell-inner'><span class='av-countdown-time ' data-upate-width='minutes'>0<\/span><span class='av-countdown-time-label ' data-label='Minute' data-label-multi='Minutes'>Minutes<\/span><\/span><\/span><span class='av-countdown-cell av-countdown-seconds'><span class='av-countdown-cell-inner'><span class='av-countdown-time ' data-upate-width='seconds'>0<\/span><span class='av-countdown-time-label ' data-label='Second(e)' data-label-multi='Secondes'>Secondes<\/span><\/span><\/span><\/span><\/div><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='av-layout-grid-1'  class='av-layout-grid-container av-1wxf1-6112715161c71ddefb8632feedf9f1e9 entry-content-wrapper main_color av-flex-cells  avia-builder-el-9  el_after_av_section  el_before_av_section  grid-row-not-first  container_wrap fullsize'  >\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kwf707ma-073da7b9a15afe90a36300b99353319c\">\n.flex_cell.av-kwf707ma-073da7b9a15afe90a36300b99353319c{\nvertical-align:top;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_cell av_one_full av-kwf707ma-073da7b9a15afe90a36300b99353319c no_margin  avia-builder-el-10  avia-builder-el-no-sibling  av-zero-padding' ><div class='flex_cell_inner'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kwf701s2-629be81fecb5564b08fde10432836048\">\n.avia-image-container.av-kwf701s2-629be81fecb5564b08fde10432836048 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-kwf701s2-629be81fecb5564b08fde10432836048 av-styling-no-styling avia-align-center  avia-builder-el-11  avia-builder-el-no-sibling  '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" class='wp-image-272 avia-img-lazy-loading-not-272 avia_image' src=\"https:\/\/moisesetlaurence.com\/wp-content\/uploads\/2025\/03\/photo2-2_ML.jpg\" alt='' title='photo2-2_ML'  height=\"812\" width=\"1914\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/moisesetlaurence.com\/wp-content\/uploads\/2025\/03\/photo2-2_ML.jpg 1914w, https:\/\/moisesetlaurence.com\/wp-content\/uploads\/2025\/03\/photo2-2_ML-300x127.jpg 300w, https:\/\/moisesetlaurence.com\/wp-content\/uploads\/2025\/03\/photo2-2_ML-1030x437.jpg 1030w, https:\/\/moisesetlaurence.com\/wp-content\/uploads\/2025\/03\/photo2-2_ML-768x326.jpg 768w, https:\/\/moisesetlaurence.com\/wp-content\/uploads\/2025\/03\/photo2-2_ML-1536x652.jpg 1536w, https:\/\/moisesetlaurence.com\/wp-content\/uploads\/2025\/03\/photo2-2_ML-1500x636.jpg 1500w, https:\/\/moisesetlaurence.com\/wp-content\/uploads\/2025\/03\/photo2-2_ML-705x299.jpg 705w\" sizes=\"(max-width: 1914px) 100vw, 1914px\" \/><\/div><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<div id='infos'  class='avia-section av-1kltl-cf3a797c036300c55344073790c21c3f main_color avia-section-large avia-no-border-styling  avia-builder-el-12  el_after_av_layout_row  el_before_av_section  avia-bg-style-scroll  container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-238'><div class='entry-content-wrapper clearfix'>\n<div class='flex_column av-2dibx-0c04909618efde5abad7680c950f4e04 av_one_fifth  avia-builder-el-13  el_before_av_three_fifth  avia-builder-el-first  first flex_column_div '   ><\/div><div class='flex_column av-1dwxd-e6e0b6445a52528d2236adce8ea08a4a av_three_fifth  avia-builder-el-14  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div '   ><p><section  class='av_textblock_section av-wkp5-ef01c295244e554c3d1357b1254c60fb '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-242 aligncenter\" role=\"img\" src=\"https:\/\/moisesetlaurence.com\/wp-content\/uploads\/2025\/03\/jour-du-mariage.svg\" alt=\"\" width=\"300\" height=\"86\" \/><\/p>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-vg41-25f43c60ce1d984552318a52730f468e '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p style=\"text-align: center;\">13 septembre, 2025<\/p>\n<p style=\"text-align: center;\">Treize septembre deux mille vingt-cinq<\/p>\n<p style=\"text-align: center;\">SALLES DE BAL LE WINDSOR<\/p>\n<\/div><\/section><\/p><\/div><div class='flex_column av-13b25-f96f7aafe6bbb8f9d91e52c7285e6772 av_one_fifth  avia-builder-el-17  el_after_av_three_fifth  el_before_av_one_fourth  flex_column_div '   ><\/div><div class='flex_column av-88js9-98f1aaf3adb6edd02c3254e3bb4a65f6 av_one_fourth  avia-builder-el-18  el_after_av_one_fifth  el_before_av_one_fourth  first flex_column_div column-top-margin'   ><\/div><div class='flex_column av-7hu7l-c938965efd284cf3a1b6758971134f47 av_one_fourth  avia-builder-el-19  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div column-top-margin'   ><section  class='av_textblock_section av-6y2y1-1f85cee0da3b09300cdc4c769aa3638d '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p style=\"text-align: center;\">15:00 &#8211; 16:00<\/p>\n<\/div><\/section><\/div><div class='flex_column av-6glp9-b75b7306ac295254ed3a414047da752c av_one_fourth  avia-builder-el-21  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div column-top-margin'   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7z67h-1f5f3b4a752e43663e0c8e0933ead285\">\n#top .hr.hr-invisible.av-7z67h-1f5f3b4a752e43663e0c8e0933ead285{\nmargin-top:-30px;\nheight:1px;\n}\n<\/style>\n<div  class='hr av-7z67h-1f5f3b4a752e43663e0c8e0933ead285 hr-invisible  avia-builder-el-22  el_before_av_textblock  avia-builder-el-first   av-desktop-hide av-medium-hide'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-m7tbpeuo-07c362caf29d62b55c0f3633bce68b7c  av-small-hide av-mini-hide'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p style=\"text-align: left;\">C\u00c9R\u00c9MONIE<br \/>\n<a href=\"https:\/\/maps.app.goo.gl\/i7AERqhSTUQCvXBz6\" target=\"_blank\" rel=\"noopener\">Cath\u00e9drale Christ Church<br \/>\n635 rue Sainte-Catherine<br \/>\nMontreal, Qu\u00e9bec H3B 1B8<\/a><\/p>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-m7tc9g9a-d181d29393b336b986908b19cc826e20  av-desktop-hide av-medium-hide'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p style=\"text-align: center;\">C\u00c9R\u00c9MONIE<br \/>\n<a href=\"https:\/\/maps.app.goo.gl\/i7AERqhSTUQCvXBz6\" target=\"_blank\" rel=\"noopener\">Cath\u00e9drale Christ Church<br \/>\n635 rue Sainte-Catherine<br \/>\nMontr\u00e9al, Qu\u00e9bec H3B 1B8<\/a><\/p>\n<\/div><\/section><\/p><\/div><div class='flex_column av-4yn3x-d5bbd19c999841876ba8182b072b99cf av_one_fourth  avia-builder-el-25  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div column-top-margin'   ><\/div><div class='flex_column av-15zfl-3089a5fe78e06bd85e520a37bee0f42c av_one_fourth  avia-builder-el-26  el_after_av_one_fourth  el_before_av_one_fourth  first flex_column_div column-top-margin'   ><\/div><div class='flex_column av-4iuo1-d7325fa12225841a35df024cbeea99f7 av_one_fourth  avia-builder-el-27  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div column-top-margin'   ><section  class='av_textblock_section av-7f5ol-a797b443ae690d9877b69dc168d6b7f5 '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p style=\"text-align: center;\">17:00 &#8211; 19:00<\/p>\n<\/div><\/section><\/div><div class='flex_column av-42rqd-9c3aa18795dbe9d0a589056780880f9a av_one_fourth  avia-builder-el-29  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div column-top-margin'   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6wfdl-f53525a5e2d9f54842dd6ff53ff19d13\">\n#top .hr.hr-invisible.av-6wfdl-f53525a5e2d9f54842dd6ff53ff19d13{\nmargin-top:-30px;\nheight:1px;\n}\n<\/style>\n<div  class='hr av-6wfdl-f53525a5e2d9f54842dd6ff53ff19d13 hr-invisible  avia-builder-el-30  el_before_av_textblock  avia-builder-el-first   av-desktop-hide av-medium-hide'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-3fgx5-141b1cd7ddaac7459e854111bab3ae9b  av-small-hide av-mini-hide'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p>COCKTAIL<br \/>\n<a href=\"https:\/\/maps.app.goo.gl\/uLeMPoX78XNw88xV6\" target=\"_blank\" rel=\"noopener\">Salles de Bal Le Windsor<br \/>\n1170 rue Peel, porte 100<br \/>\nMontr\u00e9al, Qu\u00e9bec H3B 0A9<\/a><\/p>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-6j6wt-d396eb57beee04203d8bce82b340c146  av-desktop-hide av-medium-hide'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p style=\"text-align: center;\">COCKTAIL<br \/>\n<a href=\"https:\/\/maps.app.goo.gl\/uLeMPoX78XNw88xV6\" target=\"_blank\" rel=\"noopener\">Salles de Bal Le Windsor<br \/>\n1170 rue Peel, porte 100<br \/>\nMontr\u00e9al, Qu\u00e9bec H3B 0A9<\/a><\/p>\n<\/div><\/section><\/p><\/div><div class='flex_column av-2xtqh-426ad443155de758d0fadf3986faca36 av_one_fourth  avia-builder-el-33  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div column-top-margin'   ><\/div><div class='flex_column av-5kvkl-2167aa6eb56dc625103e4509d94615e9 av_one_fourth  avia-builder-el-34  el_after_av_one_fourth  el_before_av_one_fourth  first flex_column_div column-top-margin'   ><\/div><div class='flex_column av-j1cp-2d2f7460ffb8bd6c01203c62838a0464 av_one_fourth  avia-builder-el-35  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div column-top-margin'   ><section  class='av_textblock_section av-m7tedof3-095341a890ddb8a2badbe45aa2ef1976 '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p style=\"text-align: center;\">19:00 &#8211; 23:00<\/p>\n<\/div><\/section><\/div><div class='flex_column av-4qdt5-673b20b5e1c37f1c89e6fa2f76f0f139 av_one_fourth  avia-builder-el-37  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div column-top-margin'   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3p6rl-7c1eb92be0578681fa0acb7506e334da\">\n#top .hr.hr-invisible.av-3p6rl-7c1eb92be0578681fa0acb7506e334da{\nmargin-top:-30px;\nheight:1px;\n}\n<\/style>\n<div  class='hr av-3p6rl-7c1eb92be0578681fa0acb7506e334da hr-invisible  avia-builder-el-38  el_before_av_textblock  avia-builder-el-first   av-desktop-hide av-medium-hide'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-m7teege2-874c50cdde1558551367e44b32d2e96d  av-small-hide av-mini-hide'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p>R\u00c9CEPTION<br \/>\n<a href=\"https:\/\/maps.app.goo.gl\/uLeMPoX78XNw88xV6\" target=\"_blank\" rel=\"noopener\">Salles de Bal Le Windsor<br \/>\n1170 rue Peel, porte 100<br \/>\nMontr\u00e9al, Qu\u00e9bec H3B 0A9<\/a><\/p>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-m7teek39-54ee5b9bcc92fa72fdc6386d77d1d1c9  av-desktop-hide av-medium-hide'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p style=\"text-align: center;\">R\u00c9CEPTION<br \/>\n<a href=\"https:\/\/maps.app.goo.gl\/uLeMPoX78XNw88xV6\" target=\"_blank\" rel=\"noopener\">Salles de Bal Le Windsor<br \/>\n1170 rue Peel, porte 100<br \/>\nMontr\u00e9al, Qu\u00e9bec H3B 0A9<\/a><\/p>\n<\/div><\/section><\/p><\/div><div class='flex_column av-13fx-77a5445b54da401fae27856e45df008e av_one_fourth  avia-builder-el-41  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div column-top-margin'   ><\/div><div class='flex_column av-2o09h-7abdce857bdc77ac19aef76f6286d7ad av_one_fourth  avia-builder-el-42  el_after_av_one_fourth  el_before_av_one_fourth  first flex_column_div column-top-margin'   ><\/div><div class='flex_column av-271uh-19cb8430cd7d1565ece42644bd4cd7c6 av_one_fourth  avia-builder-el-43  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div column-top-margin'   ><section  class='av_textblock_section av-m7tc46c6-ab04da0815978f2fb80197ace1198df2 '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p style=\"text-align: center;\">23:00 &#8211; 02:00<\/p>\n<\/div><\/section><\/div><div class='flex_column av-1dl1l-9a22433f065b248d87b5112268bada91 av_one_fourth  avia-builder-el-45  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div column-top-margin'   ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-m7tbs7mp-5557304a9631080270618ace20d47a2e\">\n#top .hr.hr-invisible.av-m7tbs7mp-5557304a9631080270618ace20d47a2e{\nmargin-top:-30px;\nheight:1px;\n}\n<\/style>\n<div  class='hr av-m7tbs7mp-5557304a9631080270618ace20d47a2e hr-invisible  avia-builder-el-46  el_before_av_textblock  avia-builder-el-first   av-desktop-hide av-medium-hide'><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-m7tee3o4-5088b960dd254a487a4ea893d70e4f96  av-small-hide av-mini-hide'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p>AFTER PARTY<br \/>\nAU WINDSOR !<\/p>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-m7tcckbi-6954386a48057c451422b29cf7c2b216  av-desktop-hide av-medium-hide'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p style=\"text-align: center;\">AFTER PARTY<br \/>\nAU WINDSOR !<\/p>\n<\/div><\/section><\/p><\/div><div class='flex_column av-11g8l-40e28008ef4772b010fb2ba038d06dc8 av_one_fourth  avia-builder-el-49  el_after_av_one_fourth  el_before_av_one_third  flex_column_div column-top-margin'   ><\/div><div class='flex_column av-202gh-f9040d25552ae2d986d3ade5c11be2a5 av_one_third  avia-builder-el-50  el_after_av_one_fourth  el_before_av_one_third  first flex_column_div column-top-margin'   ><\/div><div class='flex_column av-1ecz5-cff5e2d7ad56a591e7b4fbcd4a1f6bc5 av_one_third  avia-builder-el-51  el_after_av_one_third  el_before_av_one_third  flex_column_div column-top-margin'   ><section  class='av_textblock_section av-m7tc4b9m-d63fa7686ae737b505148ea0724432b6 '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-130\" role=\"img\" src=\"https:\/\/moisesetlaurence.com\/wp-content\/uploads\/2025\/03\/ML_logo.svg\" alt=\"\" width=\"100\" height=\"68\" \/><\/p>\n<\/div><\/section><\/div><div class='flex_column av-zz2p-f30e4e7e4d04be903654eb7f8bba2ea3 av_one_third  avia-builder-el-53  el_after_av_one_third  avia-builder-el-last  flex_column_div column-top-margin'   ><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='menu'  class='avia-section av-av_section-bc98e85104a520ed9264d334148d8d3a main_color avia-section-large avia-no-border-styling  avia-builder-el-54  el_after_av_section  el_before_av_section  avia-bg-style-scroll  container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-238'><div class='entry-content-wrapper clearfix'>\n<div class='flex_column av-av_one_full-a93934ecd89fbb8a9566d39e89cd3725 av_one_full  avia-builder-el-55  avia-builder-el-no-sibling  first flex_column_div '   ><section  class='av_textblock_section av-av_textblock-32af9c344aeda5838e62bcf702809feb '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><h2 style=\"text-align: center;\">INFORMATIONS<br \/>\nCOMPL\u00c9MENTAIRES<\/h2>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-82f5be0ae0af6a64fe3091010b237709\">\n#top .hr.hr-invisible.av-av_hr-82f5be0ae0af6a64fe3091010b237709{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-av_hr-82f5be0ae0af6a64fe3091010b237709 hr-invisible  avia-builder-el-57  el_after_av_textblock  el_before_av_toggle_container  '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-m8youljw-a99546288765e2f271c8cb0fb8da31d3\">\n#top .togglecontainer.av-m8youljw-a99546288765e2f271c8cb0fb8da31d3 p.toggler{\ncolor:#000000;\nbackground-color:#ffffff;\nborder-color:#000000;\n}\n#top .togglecontainer.av-m8youljw-a99546288765e2f271c8cb0fb8da31d3 p.toggler .toggle_icon{\ncolor:#000000;\nborder-color:#000000;\n}\n#top .togglecontainer.av-m8youljw-a99546288765e2f271c8cb0fb8da31d3 p.toggler .toggle_icon > span{\ncolor:#000000;\nborder-color:#000000;\n}\n#top .togglecontainer.av-m8youljw-a99546288765e2f271c8cb0fb8da31d3 .toggle_wrap .toggle_content{\ncolor:#000000;\nbackground-color:#ffffff;\nborder-color:#000000;\n}\n<\/style>\n<div  class='togglecontainer av-m8youljw-a99546288765e2f271c8cb0fb8da31d3 av-elegant-toggle  avia-builder-el-58  el_after_av_hr  avia-builder-el-last  toggle_close_all ' >\n<section class='av_toggle_section av-m8yoki70-b0f8f255bc98ff284177874af2226d35'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Tout} \"  ><p data-fake-id='#toggle-id-1' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-1'>Menu<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-1' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p style=\"text-align: center;\"><strong>ENTR\u00c9E<\/strong><\/p>\n<p style=\"text-align: center;\">La tour d\u2019antipasto \u00e0 la Toscane : prosciutto, mortadelle, capicollo et cantaloup, sur feuille de laitue Boston avec l\u00e9gumes grill\u00e9s<\/p>\n<p style=\"text-align: center;\">&#8212;<\/p>\n<p style=\"text-align: center;\"><strong>PLAT PRINCIPAL<br \/>\n(1 choix)<\/strong><\/p>\n<p style=\"text-align: center;\">Feuillet\u00e9 de veau brais\u00e9 aux champignons sauvages, pur\u00e9e de pommes de terre aux herbes, carottes \u00e0 tige r\u00f4ties et asperges grill\u00e9es<\/p>\n<p style=\"text-align: center;\">OU<\/p>\n<p style=\"text-align: center;\">Filet de saumon po\u00eal\u00e9 au beurre et vin blanc, couscous isra\u00e9lien et l\u00e9gumes grill\u00e9s<\/p>\n<p style=\"text-align: center;\">OU<\/p>\n<p style=\"text-align: center;\">Steak de chou-fleur, couscous isra\u00e9lien, l\u00e9gumes grill\u00e9s (v\u00e9gane)<\/p>\n<p style=\"text-align: center;\">&#8212;<\/p>\n<p style=\"text-align: center;\"><strong>DESSERT<\/strong><\/p>\n<p style=\"text-align: center;\">G\u00e2teau des mari\u00e9s<\/p>\n<p style=\"text-align: center;\">Table de minuit: bouch\u00e9es sucr\u00e9es et sal\u00e9es assorties<\/p>\n<p style=\"text-align: center;\">&#8212;<\/p>\n<p style=\"text-align: center;\"><strong>*Simplement nous aviser si vous avez des allergies\/intol\u00e9rance et\/ou restrictions alimentaires*<\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-av_toggle-b3d0b30525ce2b1ec7a5a979eb68909f'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Tout} \"  ><p data-fake-id='#toggle-id-2' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-2'>Y aura-t-il un bar \u00e0 volont\u00e9 ?<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-2' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>Oui, un bar complet sera \u00e0 votre disposition avec des boissons \u00e0 volont\u00e9 toute la soir\u00e9e.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-m8yolc7q-eab9ed122c07a170e3a235a1df7a65d2'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Tout} \"  ><p data-fake-id='#toggle-id-3' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-3'>Puis-je venir accompagn\u00e9(e) ?<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-3' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>Bien s\u00fbr que vous pouvez. Plus il y a d\u2019invit\u00e9s, plus la f\u00eate sera joyeuse. Il suffira d\u2019inscrire le nom de votre\/vos invit\u00e9(s) avec son choix de repas <a href=\"https:\/\/moisesetlaurence.com\/fr\/#confirmer\"><u>ici-bas<\/u><\/a>.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-m8yonucy-e4afacb0ac24a70d27f06becc5ca4e07'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Tout} \"  ><p data-fake-id='#toggle-id-4' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-4'>Les enfants sont-ils invit\u00e9s ?<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-4' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>Bien que nous adorons vos enfants, nous avons d\u00e9cid\u00e9 de r\u00e9server notre mariage aux enfants de 12 ans et plus.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-m91cy2xk-c1a8c90f9f75e48c14e8f22fd43bfa47'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Tout} \"  ><p data-fake-id='#toggle-id-5' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-5'>\u00c0 quelle heure dois-je arriver ?<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-5' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>Bien que la c\u00e9r\u00e9monie commence \u00e0 15:00, nous recommandons aux invit\u00e9s d&rsquo;arriver au moins 20 minutes avant, afin que vous puissiez vous garer et vous assurer d&rsquo;\u00eatre \u00e0 l&rsquo;heure.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-m8yoppg9-0aa3585339b8bc430a72e222144fde89'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Tout} \"  ><p data-fake-id='#toggle-id-6' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-6'>O\u00f9 puis-je me stationner ?<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-6' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p><strong>STATIONNEMENT \u00c9GLISE<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/maps.app.goo.gl\/zS2HAzmm8Y8mn4fZ7?g_st=com.google.maps.preview.copy\" target=\"_blank\" rel=\"noopener\"><u>Ext\u00e9rieur<\/u><\/a><\/li>\n<li><a href=\"https:\/\/maps.app.goo.gl\/JEUGQfvHMr8UvHS16?g_st=com.google.maps.preview.copy\" target=\"_blank\" rel=\"noopener\"><u>Int\u00e9rieur<\/u><\/a><\/li>\n<\/ul>\n<p><strong>STATIONNEMENT R\u00c9CEPTION<\/strong><\/p>\n<p>Int\u00e9rieur<\/p>\n<ul>\n<li><a href=\"https:\/\/maps.app.goo.gl\/CvwoMDF7C3R2aj926?g_st=com.google.maps.preview.copy\" target=\"_blank\" rel=\"noopener\"><u>Option 1<\/u><\/a><\/li>\n<li><a href=\"https:\/\/maps.app.goo.gl\/48rmRv2ftfV78SRX8?g_st=com.google.maps.preview.copy\" target=\"_blank\" rel=\"noopener\"><u>Option 2<\/u><\/a><\/li>\n<li><a href=\"https:\/\/maps.app.goo.gl\/hsppjMhzvKhm9Rxw8?g_st=com.google.maps.preview.copy\" target=\"_blank\" rel=\"noopener\"><u>Option 3<\/u><\/a><\/li>\n<\/ul>\n<p><a href=\"https:\/\/maps.app.goo.gl\/Sey88QHrRu7QRwnT8?g_st=com.google.maps.preview.copy\" target=\"_blank\" rel=\"noopener\"><u>Ext\u00e9rieur<\/u><\/a><\/p>\n<p>* Veuillez noter que la c\u00e9r\u00e9monie se d\u00e9roule \u00e0 quelques minutes \u00e0 pied de la r\u00e9ception.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-m8york82-b167222c4ac0663a0f7adf6c79aa7bda'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Tout} \"  ><p data-fake-id='#toggle-id-7' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-7'>O\u00f9 puis-je me loger?<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-7' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p><a href=\"https:\/\/www.marriott.com\/en-us\/hotels\/yulsi-le-centre-sheraton-montreal-hotel\/overview\/?scid=f2ae0541-1279-4f24-b197-a979c79310b0\" target=\"_blank\" rel=\"noopener\"><u>H\u00f4tel Sheraton Montr\u00e9al<\/u><\/a><\/p>\n<p><a href=\"https:\/\/www.marriott.com\/en-us\/hotels\/yulcc-montreal-marriott-chateau-champlain\/overview\/?scid=f2ae0541-1279-4f24-b197-a979c79310b0\" target=\"_blank\" rel=\"noopener\"><u>H\u00f4tel Marriott Ch\u00e2teau Champlain<\/u><\/a><\/p>\n<p><a href=\"https:\/\/www.fairmont.com\/queen-elizabeth-montreal\/?goto=fiche_hotel&amp;code_hotel=A567&amp;merchantid=seo-maps-CA-A567&amp;sourceid=aw-cen&amp;utm_medium=seo%20maps&amp;utm_source=google%20Maps&amp;utm_campaign=seo%20maps\" target=\"_blank\" rel=\"noopener\"><u>H\u00f4tel Fairmont Le Reine \u00c9lizabeth<\/u><\/a><\/p>\n<p>*Nous vous sugg\u00e9rons de r\u00e9server votre h\u00e9bergement rapidement afin de garantir la disponibilit\u00e9.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-m8yosj2q-23aa1e4526faf2b5dafbbf8d959dadd8'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Tout} \"  ><p data-fake-id='#toggle-id-8' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-8'>Comment puis-je confirmer ma pr\u00e9sence ?<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-8' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>Nous serions ravis de vous avoir \u00e0 nos c\u00f4t\u00e9s pour c\u00e9l\u00e9brer ce moment pr\u00e9cieux. Pour pouvoir participer \u00e0 cette journ\u00e9e sp\u00e9ciale, une contribution de 150 $ par personne est demand\u00e9e. Veuillez confirmer votre pr\u00e9sence en compl\u00e9tant les champs du <a href=\"https:\/\/moisesetlaurence.com\/fr\/#confirmer\"><u>formulaire<\/u><\/a> un peu plus bas, au plus tard le 15 juillet 2025.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-av_toggle-0e81c35b5c985b9903a2ba0a90d2c08e'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Tout} \"  ><p data-fake-id='#toggle-id-9' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-9'>Comment puis-je payer ?<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-9' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>Veuillez envoyer votre contribution par virement Interac au courriel suivant :<br \/>\n<a href=\"mailto:wedding@moisesetlaurence.com\">wedding@moisesetlaurence.com<\/a><br \/>\nMot de passe : Love<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-m8yotur6-ce6fe5f2cb9084dd21fbc235e7e5833d'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{Tout} \"  ><p data-fake-id='#toggle-id-10' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-10'>Y a-t-il une liste de cadeaux ?<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-10' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>Votre pr\u00e9sence est plus que suffisante ! Bien que nous n&rsquo;ayons pas de liste de cadeaux traditionnelle, le jour venu, nous mettrons une bo\u00eete \u00e0 votre disposition \u00e0 la r\u00e9ception. Sachez que c\u2019est enti\u00e8rement facultatif. L\u2019essentiel est que vous soyez l\u00e0 pour cr\u00e9er des souvenirs inoubliables lors de notre grand jour !<\/p>\n<\/div><\/div><\/div><\/section>\n<\/div><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='confirmer'  class='avia-section av-kwf8iyrg-77c5ba5a438f9a52fa0d14ece4867353 main_color avia-section-large avia-no-border-styling  avia-builder-el-59  el_after_av_section  avia-builder-el-last  avia-bg-style-scroll  container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-238'><div class='entry-content-wrapper clearfix'>\n<div class='flex_column av-1pu3d-fc384f4dafc18b6ae6c491f178b5c2d8 av_one_fifth  avia-builder-el-60  el_before_av_three_fifth  avia-builder-el-first  first flex_column_div '   ><\/div><div class='flex_column av-10bkp-a4280fa84af7ae4670eecf5cbf6a078f av_three_fifth  avia-builder-el-61  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div '   ><section  class='av_textblock_section av-kwf88lra-71d0ac11dd100f21017f690a21cdb121 '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><h2 style=\"text-align: center;\">CONFIRMER MA PR\u00c9SENCE<\/h2>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-m7ti1ug3-8c9a813ad6fef5eeef8add43a660f8a6 '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p style=\"text-align: center;\"><a href=\"https:\/\/moisesetlaurence.com\/fr\/#toggle-id-1\"><strong>Pour plus de d\u00e9tails sur le menu, consultez les informations compl\u00e9mentaires ci-dessus.<\/strong><\/a><\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1002t-b32cc56806b632cad4440af07f81e70a\">\n#top .hr.hr-invisible.av-1002t-b32cc56806b632cad4440af07f81e70a{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-1002t-b32cc56806b632cad4440af07f81e70a hr-invisible  avia-builder-el-64  el_after_av_textblock  el_before_av_textblock  '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-kwf8jh8f-62651777ac0ebcf489b3d908572fdc51 '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock '  itemprop=\"text\" ><p style=\"text-align: center;\"><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-253\"><form id=\"wpforms-form-253\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"253\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/fr\/wp-json\/wp\/v2\/pages\/238\" data-token=\"f6bcedcfbc87d19009d2a757e6815877\" data-token-time=\"1788329228\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-253-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-253-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" placeholder=\"Pr\u00e9nom\" aria-errormessage=\"wpforms-253-field_1-error\" required><label for=\"wpforms-253-field_1\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-253-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" placeholder=\"Nom\" aria-errormessage=\"wpforms-253-field_1-last-error\" required><label for=\"wpforms-253-field_1-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-253-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-253-field_2\" aria-hidden=\"false\">Courriel <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-253-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Courriel\" spellcheck=\"false\" aria-errormessage=\"wpforms-253-field_2-error\" required><\/div><div id=\"wpforms-253-field_3-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-trigger\" data-field-id=\"3\"><fieldset><legend class=\"wpforms-field-label\">Pr\u00e9sence au mariage <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-253-field_3\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_3_1\" name=\"wpforms[fields][3]\" value=\"Je serai pr\u00e9sent(e)\" aria-errormessage=\"wpforms-253-field_3_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_3_1\">Je serai pr\u00e9sent(e)<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_3_2\" name=\"wpforms[fields][3]\" value=\"Malheureusement, je ne serai pas pr\u00e9sent(e)\" aria-errormessage=\"wpforms-253-field_3_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_3_2\">Malheureusement, je ne serai pas pr\u00e9sent(e)<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-253-field_7-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"7\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">MENU - Plat principal du 1er(e) invit\u00e9(e)<\/legend><ul id=\"wpforms-253-field_7\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_7_1\" name=\"wpforms[fields][7]\" value=\"Veau brais\u00e9\" aria-errormessage=\"wpforms-253-field_7_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_7_1\">Veau brais\u00e9<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_7_2\" name=\"wpforms[fields][7]\" value=\"Filet de saumon\" aria-errormessage=\"wpforms-253-field_7_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_7_2\">Filet de saumon<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_7_7\" name=\"wpforms[fields][7]\" value=\"Steak de chou-fleur (v\u00e9gane)\" aria-errormessage=\"wpforms-253-field_7_7-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_7_7\">Steak de chou-fleur (v\u00e9gane)<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-253-field_16-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"16\" style=\"display:none;\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-253-field_16\" aria-hidden=\"false\">Allergies<\/label><input type=\"text\" id=\"wpforms-253-field_16\" class=\"wpforms-field-large\" name=\"wpforms[fields][16]\" placeholder=\"Allergies, intol\u00e9rances et\/ou restrictions alimentaires\" aria-errormessage=\"wpforms-253-field_16-error\" ><\/div><div id=\"wpforms-253-field_8-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-id=\"8\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">Seras-tu accompagn\u00e9(e)? <\/legend><ul id=\"wpforms-253-field_8\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_8_1\" name=\"wpforms[fields][8]\" value=\"Oui\" aria-errormessage=\"wpforms-253-field_8_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_8_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_8_2\" name=\"wpforms[fields][8]\" value=\"Non\" aria-errormessage=\"wpforms-253-field_8_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_8_2\">Non<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-253-field_11-container\" class=\"wpforms-field wpforms-field-name wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"11\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">2e invit\u00e9(e)<\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-253-field_11\" class=\"wpforms-field-name-first\" name=\"wpforms[fields][11][first]\" placeholder=\"Pr\u00e9nom\" aria-errormessage=\"wpforms-253-field_11-error\" ><label for=\"wpforms-253-field_11\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-253-field_11-last\" class=\"wpforms-field-name-last\" name=\"wpforms[fields][11][last]\" placeholder=\"Nom\" aria-errormessage=\"wpforms-253-field_11-last-error\" ><label for=\"wpforms-253-field_11-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-253-field_20-container\" class=\"wpforms-field wpforms-field-email wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"20\" style=\"display:none;\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-253-field_20\" aria-hidden=\"false\">Courriel 2 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-253-field_20\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][20]\" placeholder=\"Courriel\" spellcheck=\"false\" aria-errormessage=\"wpforms-253-field_20-error\" required><\/div><div id=\"wpforms-253-field_15-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"15\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">MENU - Plat principal du 2e invit\u00e9(e)<\/legend><ul id=\"wpforms-253-field_15\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_15_1\" name=\"wpforms[fields][15]\" value=\"Veau brais\u00e9\" aria-errormessage=\"wpforms-253-field_15_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_15_1\">Veau brais\u00e9<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_15_2\" name=\"wpforms[fields][15]\" value=\"Filet de saumon\" aria-errormessage=\"wpforms-253-field_15_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_15_2\">Filet de saumon<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_15_7\" name=\"wpforms[fields][15]\" value=\"Steak de chou-fleur (v\u00e9gane)\" aria-errormessage=\"wpforms-253-field_15_7-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_15_7\">Steak de chou-fleur (v\u00e9gane)<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-253-field_21-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"21\" style=\"display:none;\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-253-field_21\" aria-hidden=\"false\">Allergies 2<\/label><input type=\"text\" id=\"wpforms-253-field_21\" class=\"wpforms-field-large\" name=\"wpforms[fields][21]\" placeholder=\"Allergies, intol\u00e9rances et\/ou restrictions alimentaires\" aria-errormessage=\"wpforms-253-field_21-error\" ><\/div><div id=\"wpforms-253-field_18-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-id=\"18\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">D\u00e9sires-tu inscrire un(e) autre invit\u00e9(e)?<\/legend><ul id=\"wpforms-253-field_18\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_18_1\" name=\"wpforms[fields][18]\" value=\"Oui\" aria-errormessage=\"wpforms-253-field_18_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_18_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_18_2\" name=\"wpforms[fields][18]\" value=\"Non\" aria-errormessage=\"wpforms-253-field_18_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_18_2\">Non<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-253-field_19-container\" class=\"wpforms-field wpforms-field-name wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"19\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">3e invit\u00e9(e)<\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-253-field_19\" class=\"wpforms-field-name-first\" name=\"wpforms[fields][19][first]\" placeholder=\"Pr\u00e9nom\" aria-errormessage=\"wpforms-253-field_19-error\" ><label for=\"wpforms-253-field_19\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-253-field_19-last\" class=\"wpforms-field-name-last\" name=\"wpforms[fields][19][last]\" placeholder=\"Nom\" aria-errormessage=\"wpforms-253-field_19-last-error\" ><label for=\"wpforms-253-field_19-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-253-field_22-container\" class=\"wpforms-field wpforms-field-email wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"22\" style=\"display:none;\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-253-field_22\" aria-hidden=\"false\">Courriel 3 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-253-field_22\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][22]\" placeholder=\"Courriel\" spellcheck=\"false\" aria-errormessage=\"wpforms-253-field_22-error\" required><\/div><div id=\"wpforms-253-field_24-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"24\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">MENU - Plat principal du 3e invit\u00e9(e)<\/legend><ul id=\"wpforms-253-field_24\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_24_1\" name=\"wpforms[fields][24]\" value=\"Veau brais\u00e9\" aria-errormessage=\"wpforms-253-field_24_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_24_1\">Veau brais\u00e9<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_24_2\" name=\"wpforms[fields][24]\" value=\"Filet de saumon\" aria-errormessage=\"wpforms-253-field_24_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_24_2\">Filet de saumon<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_24_7\" name=\"wpforms[fields][24]\" value=\"Steak de chou-fleur (v\u00e9gane)\" aria-errormessage=\"wpforms-253-field_24_7-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_24_7\">Steak de chou-fleur (v\u00e9gane)<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-253-field_23-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"23\" style=\"display:none;\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-253-field_23\" aria-hidden=\"false\">Allergies 3<\/label><input type=\"text\" id=\"wpforms-253-field_23\" class=\"wpforms-field-large\" name=\"wpforms[fields][23]\" placeholder=\"Allergies, intol\u00e9rances et\/ou restrictions alimentaires\" aria-errormessage=\"wpforms-253-field_23-error\" ><\/div><div id=\"wpforms-253-field_26-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-id=\"26\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">D\u00e9sires-tu inscrire un(e) autre invit\u00e9(e)?<\/legend><ul id=\"wpforms-253-field_26\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_26_1\" name=\"wpforms[fields][26]\" value=\"Oui\" aria-errormessage=\"wpforms-253-field_26_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_26_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_26_2\" name=\"wpforms[fields][26]\" value=\"Non\" aria-errormessage=\"wpforms-253-field_26_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_26_2\">Non<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-253-field_25-container\" class=\"wpforms-field wpforms-field-name wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"25\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">4e invit\u00e9(e)<\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-253-field_25\" class=\"wpforms-field-name-first\" name=\"wpforms[fields][25][first]\" placeholder=\"Pr\u00e9nom\" aria-errormessage=\"wpforms-253-field_25-error\" ><label for=\"wpforms-253-field_25\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-253-field_25-last\" class=\"wpforms-field-name-last\" name=\"wpforms[fields][25][last]\" placeholder=\"Nom\" aria-errormessage=\"wpforms-253-field_25-last-error\" ><label for=\"wpforms-253-field_25-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-253-field_27-container\" class=\"wpforms-field wpforms-field-email wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"27\" style=\"display:none;\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-253-field_27\" aria-hidden=\"false\">Courriel 4 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-253-field_27\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][27]\" placeholder=\"Courriel\" spellcheck=\"false\" aria-errormessage=\"wpforms-253-field_27-error\" required><\/div><div id=\"wpforms-253-field_29-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"29\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">MENU - Plat principal du 4e invit\u00e9(e)<\/legend><ul id=\"wpforms-253-field_29\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_29_1\" name=\"wpforms[fields][29]\" value=\"Veau brais\u00e9\" aria-errormessage=\"wpforms-253-field_29_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_29_1\">Veau brais\u00e9<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_29_2\" name=\"wpforms[fields][29]\" value=\"Filet de saumon\" aria-errormessage=\"wpforms-253-field_29_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_29_2\">Filet de saumon<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_29_7\" name=\"wpforms[fields][29]\" value=\"Steak de chou-fleur (v\u00e9gane)\" aria-errormessage=\"wpforms-253-field_29_7-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_29_7\">Steak de chou-fleur (v\u00e9gane)<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-253-field_28-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"28\" style=\"display:none;\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-253-field_28\" aria-hidden=\"false\">Allergies 4<\/label><input type=\"text\" id=\"wpforms-253-field_28\" class=\"wpforms-field-large\" name=\"wpforms[fields][28]\" placeholder=\"Allergies, intol\u00e9rances et\/ou restrictions alimentaires\" aria-errormessage=\"wpforms-253-field_28-error\" ><\/div><div id=\"wpforms-253-field_34-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-id=\"34\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">D\u00e9sires-tu inscrire un(e) autre invit\u00e9(e)?<\/legend><ul id=\"wpforms-253-field_34\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_34_1\" name=\"wpforms[fields][34]\" value=\"Oui\" aria-errormessage=\"wpforms-253-field_34_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_34_1\">Oui<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_34_2\" name=\"wpforms[fields][34]\" value=\"Non\" aria-errormessage=\"wpforms-253-field_34_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_34_2\">Non<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-253-field_30-container\" class=\"wpforms-field wpforms-field-name wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"30\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">5e invit\u00e9(e)<\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-253-field_30\" class=\"wpforms-field-name-first\" name=\"wpforms[fields][30][first]\" placeholder=\"Pr\u00e9nom\" aria-errormessage=\"wpforms-253-field_30-error\" ><label for=\"wpforms-253-field_30\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-253-field_30-last\" class=\"wpforms-field-name-last\" name=\"wpforms[fields][30][last]\" placeholder=\"Nom\" aria-errormessage=\"wpforms-253-field_30-last-error\" ><label for=\"wpforms-253-field_30-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-253-field_31-container\" class=\"wpforms-field wpforms-field-email wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"31\" style=\"display:none;\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-253-field_31\" aria-hidden=\"false\">Courriel 5 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-253-field_31\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][31]\" placeholder=\"Courriel\" spellcheck=\"false\" aria-errormessage=\"wpforms-253-field_31-error\" required><\/div><div id=\"wpforms-253-field_32-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"32\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">MENU - Plat principal du 5e invit\u00e9(e)<\/legend><ul id=\"wpforms-253-field_32\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_32_1\" name=\"wpforms[fields][32]\" value=\"Veau brais\u00e9\" aria-errormessage=\"wpforms-253-field_32_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_32_1\">Veau brais\u00e9<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_32_2\" name=\"wpforms[fields][32]\" value=\"Filet de saumon\" aria-errormessage=\"wpforms-253-field_32_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_32_2\">Filet de saumon<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-253-field_32_7\" name=\"wpforms[fields][32]\" value=\"Steak de chou-fleur (v\u00e9gane)\" aria-errormessage=\"wpforms-253-field_32_7-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-253-field_32_7\">Steak de chou-fleur (v\u00e9gane)<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-253-field_33-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"33\" style=\"display:none;\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-253-field_33\" aria-hidden=\"false\">Allergies 5<\/label><input type=\"text\" id=\"wpforms-253-field_33\" class=\"wpforms-field-large\" name=\"wpforms[fields][33]\" placeholder=\"Allergies, intol\u00e9rances et\/ou restrictions alimentaires\" aria-errormessage=\"wpforms-253-field_33-error\" ><\/div><div id=\"wpforms-253-field_17-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"17\"><label class=\"wpforms-field-label\" for=\"wpforms-253-field_17\">Demande(s) sp\u00e9ciale(s)<\/label><textarea id=\"wpforms-253-field_17\" class=\"wpforms-field-medium\" name=\"wpforms[fields][17]\" aria-errormessage=\"wpforms-253-field_17-error\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"253\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/moisesetlaurence.com\/fr\/wp-json\/wp\/v2\/pages\/238\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-253\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moisesetlaurence.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/p>\n<\/div><\/section><\/p><\/div><div class='flex_column av-1359t-3ca37f0423fb5f62635f974382ace76c av_one_fifth  avia-builder-el-66  el_after_av_three_fifth  avia-builder-el-last  flex_column_div '   ><\/div>\n<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":192,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-238","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/moisesetlaurence.com\/fr\/wp-json\/wp\/v2\/pages\/238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moisesetlaurence.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/moisesetlaurence.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/moisesetlaurence.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/moisesetlaurence.com\/fr\/wp-json\/wp\/v2\/comments?post=238"}],"version-history":[{"count":29,"href":"https:\/\/moisesetlaurence.com\/fr\/wp-json\/wp\/v2\/pages\/238\/revisions"}],"predecessor-version":[{"id":378,"href":"https:\/\/moisesetlaurence.com\/fr\/wp-json\/wp\/v2\/pages\/238\/revisions\/378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moisesetlaurence.com\/fr\/wp-json\/wp\/v2\/media\/192"}],"wp:attachment":[{"href":"https:\/\/moisesetlaurence.com\/fr\/wp-json\/wp\/v2\/media?parent=238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}